{"id":95,"date":"2025-06-13T22:40:38","date_gmt":"2025-06-14T01:40:38","guid":{"rendered":"https:\/\/gpkbrasil.com\/produto\/livro-bloco-criativo-8-cores-a3-120-gsm-com-32-folhas\/"},"modified":"2026-07-14T18:28:42","modified_gmt":"2026-07-14T21:28:42","slug":"livro-bloco-criativo-8-cores-a3-120-gsm-com-32-folhas","status":"publish","type":"product","link":"https:\/\/gpkbrasil.com.br\/b2b\/produto\/livro-bloco-criativo-8-cores-a3-120-gsm-com-32-folhas\/","title":{"rendered":"Bloco Criativo 8 Cores A3 120 Alta Gramatura 32 Folhas + Atividades 30&#215;42 cm Sortido Romitec"},"content":{"rendered":"<h3 style=\"margin-top: 18px; margin-bottom: 8px;\">Apresenta\u00e7\u00e3o do produto<\/h3>\n<p style=\"line-height: 1.6; margin-bottom: 12px;\">O Bloco Criativo Romitec A3 \u00e9 um material educativo completo desenvolvido para estimular a criatividade, o aprendizado e a express\u00e3o art\u00edstica de crian\u00e7as e jovens. Amplamente utilizado em escolas de todo o Brasil, este kit combina papel colorido de alta qualidade com um livro pedag\u00f3gico tril\u00edngue, proporcionando uma experi\u00eancia de aprendizado l\u00fadica e interativa. Ideal para atividades escolares, trabalhos art\u00edsticos, projetos pedag\u00f3gicos, artesanato e momentos criativos em casa, o Bloco Criativo Romitec oferece um formato A3, que proporciona mais espa\u00e7o para desenhar, pintar, recortar, dobrar e criar.<\/p>\n<h3 style=\"margin-top: 18px; margin-bottom: 8px;\">Qualidade e materiais<\/h3>\n<ul style=\"padding-left: 18px; margin-top: 6px; margin-bottom: 14px;\">\n<li style=\"margin-bottom: 4px;\">Material: Papel (offset) | Cart\u00e3o | Cola| Cor: Sortido | Gramatura 120 g\/m\u00b2<\/li>\n<\/ul>\n<h3 style=\"margin-top: 18px; margin-bottom: 8px;\">Dimens\u00f5es e conte\u00fado<\/h3>\n<ul style=\"padding-left: 18px; margin-top: 6px; margin-bottom: 14px;\">\n<li style=\"margin-bottom: 4px;\">Formato A3<\/li>\n<li style=\"margin-bottom: 4px;\">Medida do produto 42 x 29,7 cm<\/li>\n<li style=\"margin-bottom: 4px;\">Quantidade da embalagem 32 folhas<\/li>\n<li style=\"margin-bottom: 4px;\">Conte\u00fado adicional livro pedag\u00f3gico tril\u00edngue com 16 p\u00e1ginas<\/li>\n<\/ul>\n<h3 style=\"margin-top: 18px; margin-bottom: 8px;\">Aplica\u00e7\u00f5es e uso<\/h3>\n<ul style=\"padding-left: 18px; margin-top: 6px; margin-bottom: 14px;\">\n<li style=\"margin-bottom: 4px;\">Atividades escolares e pedag\u00f3gicas Trabalhos de artes e criatividade Projetos de colagem, dobradura e recorte Apresenta\u00e7\u00f5es escolares Desenvolvimento art\u00edstico infantil Atividades educativas entre pais e filhos.<\/li>\n<\/ul>\n<h3 style=\"margin-top: 18px; margin-bottom: 8px;\">Diferenciais<\/h3>\n<ul style=\"padding-left: 18px; margin-top: 6px; margin-bottom: 14px;\">\n<li style=\"margin-bottom: 4px;\">Linha voltada para cria\u00e7\u00e3o, aprendizagem e trabalhos manuais, reunindo especifica\u00e7\u00f5es \u00fateis para uso escolar e art\u00edstico.<\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>O Bloco Criativo Romitec A3 \u00e9 um material educativo completo desenvolvido para estimular a criatividade, o aprendizado e a express\u00e3o art\u00edstica de crian\u00e7as.<\/p>\n","protected":false},"featured_media":5203,"comment_status":"open","ping_status":"closed","template":"","meta":{"_kad_post_transparent":"default","_kad_post_title":"","_kad_post_layout":"default","_kad_post_sidebar_id":"","_kad_post_content_style":"default","_kad_post_vertical_padding":"default","_kad_post_feature":"","_kad_post_feature_position":"","_kad_post_header":false,"_kad_post_footer":false,"_kad_post_classname":""},"product_brand":[96],"product_cat":[32,29],"product_tag":[95],"class_list":["post-95","product","type-product","status-publish","has-post-thumbnail","product_brand-romitec","product_cat-livro-dobradura","product_cat-pedagogico-livro","product_tag-ofertas","pa_cor-sortido","pa_encadernacao-grampeado","pa_gramatura-120-gsm","pa_marca-romitec","pa_material-papel-offset-cartao-aco","pa_quantidade-do-conteudo-16-paginas-32-folhas","pa_sustentabilidade-fsc-i-rec","pa_tamanho-297-mm-x-420-mm","first","instock","sale","featured","shipping-taxable","product-type-simple","entry","content-bg","loop-entry"],"_links":{"self":[{"href":"https:\/\/gpkbrasil.com.br\/b2b\/wp-json\/wp\/v2\/product\/95","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/gpkbrasil.com.br\/b2b\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/gpkbrasil.com.br\/b2b\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/gpkbrasil.com.br\/b2b\/wp-json\/wp\/v2\/comments?post=95"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/gpkbrasil.com.br\/b2b\/wp-json\/wp\/v2\/media\/5203"}],"wp:attachment":[{"href":"https:\/\/gpkbrasil.com.br\/b2b\/wp-json\/wp\/v2\/media?parent=95"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/gpkbrasil.com.br\/b2b\/wp-json\/wp\/v2\/product_brand?post=95"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/gpkbrasil.com.br\/b2b\/wp-json\/wp\/v2\/product_cat?post=95"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/gpkbrasil.com.br\/b2b\/wp-json\/wp\/v2\/product_tag?post=95"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}