{"id":3149,"date":"2025-08-25T18:05:46","date_gmt":"2025-08-25T21:05:46","guid":{"rendered":"https:\/\/gpkbrasil.com\/produto\/pasta-catalogo-pp-oficio-clear-plastic-folder-20-sacos-azul-pastel-com-10\/"},"modified":"2026-07-14T18:29:23","modified_gmt":"2026-07-14T21:29:23","slug":"pasta-catalogo-pp-oficio-clear-plastic-folder-20-sacos-azul-pastel-com-10","status":"publish","type":"product","link":"https:\/\/gpkbrasil.com.br\/b2b\/produto\/pasta-catalogo-pp-oficio-clear-plastic-folder-20-sacos-azul-pastel-com-10\/","title":{"rendered":"Pasta Cat\u00e1logo Of\u00edcio Clear Plastic Folder 20 Sacos PP 23&#215;33 cm Azul 10 Unidades PlastPark"},"content":{"rendered":"<h3 style=\"margin-top:18px;margin-bottom:8px;\">Apresenta\u00e7\u00e3o do produto<\/h3>\n<p style=\"line-height:1.6; margin-bottom:12px;\">A Pasta Cat\u00e1logo PlastPark Clear P Folder PP 20S Azull c\/10 foi desenvolvida para organizar, proteger e apresentar documentos, cat\u00e1logos, propostas, mostru\u00e1rios e materiais de consulta com praticidade Especifica\u00e7\u00f5es principais: medida 33,2 x 23 cm, material: PP, cor Azul.<\/p>\n<h3 style=\"margin-top:18px;margin-bottom:8px;\">Qualidade e materiais<\/h3>\n<ul style=\"padding-left:18px; margin-top:6px; margin-bottom:14px;\">\n<li style=\"margin-bottom:4px;\">Material: PP | Cor: Azul<\/li>\n<\/ul>\n<h3 style=\"margin-top:18px;margin-bottom:8px;\">Dimens\u00f5es e conte\u00fado<\/h3>\n<ul style=\"padding-left:18px; margin-top:6px; margin-bottom:14px;\">\n<li style=\"margin-bottom:4px;\">Medida do produto 33,2 x 23 cm<\/li>\n<\/ul>\n<h3 style=\"margin-top:18px;margin-bottom:8px;\">Aplica\u00e7\u00f5es e uso<\/h3>\n<ul style=\"padding-left:18px; margin-top:6px; margin-bottom:14px;\">\n<li style=\"margin-bottom:4px;\">apresenta\u00e7\u00e3o de cat\u00e1logos, propostas, portf\u00f3lios, documentos, mostru\u00e1rios, materiais comerciais e arquivos de consulta.<\/li>\n<\/ul>\n<h3 style=\"margin-top:18px;margin-bottom:8px;\">Diferenciais<\/h3>\n<ul style=\"padding-left:18px; margin-top:6px; margin-bottom:14px;\">\n<li style=\"margin-bottom:4px;\">Ajuda a conservar documentos e melhora a apresenta\u00e7\u00e3o, separa\u00e7\u00e3o e manuseio dos materiais no dia a dia.<\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>A Pasta Cat\u00e1logo PlastPark Clear P Folder PP 20S Azull c\/10 foi desenvolvida para organizar, proteger e apresentar documentos, cat\u00e1logos, propostas.<\/p>\n","protected":false},"featured_media":3148,"comment_status":"open","ping_status":"closed","template":"","meta":{"_kad_post_transparent":"","_kad_post_title":"","_kad_post_layout":"","_kad_post_sidebar_id":"","_kad_post_content_style":"","_kad_post_vertical_padding":"","_kad_post_feature":"","_kad_post_feature_position":"","_kad_post_header":false,"_kad_post_footer":false,"_kad_post_classname":""},"product_brand":[97],"product_cat":[39,28],"product_tag":[],"class_list":["post-3149","product","type-product","status-publish","has-post-thumbnail","product_brand-plastpark","product_cat-pasta-catalogo","product_cat-pasta","pa_cor-azul","pa_encadernacao-solda-eletronica","pa_espessura-0-09-mm-miolo-0-60-mm-capa","pa_marca-plastpark","pa_material-pp","pa_quantidade-do-conteudo-20-sacos","pa_sustentabilidade-i-rec-go-green-p-life","pa_tamanho-of-230-mm-x-332-mm","first","instock","shipping-taxable","product-type-simple","entry","content-bg","loop-entry"],"_links":{"self":[{"href":"https:\/\/gpkbrasil.com.br\/b2b\/wp-json\/wp\/v2\/product\/3149","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/gpkbrasil.com.br\/b2b\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/gpkbrasil.com.br\/b2b\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/gpkbrasil.com.br\/b2b\/wp-json\/wp\/v2\/comments?post=3149"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/gpkbrasil.com.br\/b2b\/wp-json\/wp\/v2\/media\/3148"}],"wp:attachment":[{"href":"https:\/\/gpkbrasil.com.br\/b2b\/wp-json\/wp\/v2\/media?parent=3149"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/gpkbrasil.com.br\/b2b\/wp-json\/wp\/v2\/product_brand?post=3149"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/gpkbrasil.com.br\/b2b\/wp-json\/wp\/v2\/product_cat?post=3149"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/gpkbrasil.com.br\/b2b\/wp-json\/wp\/v2\/product_tag?post=3149"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}