{"id":17,"date":"2025-06-25T13:37:41","date_gmt":"2025-06-25T16:37:41","guid":{"rendered":"https:\/\/gpkbrasil.com\/?page_id=17"},"modified":"2025-11-06T13:37:29","modified_gmt":"2025-11-06T16:37:29","slug":"reembolso-devolucoes","status":"publish","type":"page","link":"https:\/\/gpkbrasil.com.br\/b2b\/reembolso-devolucoes\/","title":{"rendered":"Pol\u00edtica de reembolso e devolu\u00e7\u00f5es"},"content":{"rendered":"<p data-start=\"447\" data-end=\"666\">A <strong data-start=\"449\" data-end=\"463\">GPK Brasil<\/strong> assegura aos seus clientes uma pol\u00edtica de trocas e devolu\u00e7\u00f5es transparente, em conformidade com o <strong data-start=\"563\" data-end=\"603\">C\u00f3digo de Defesa do Consumidor (CDC)<\/strong> e com pr\u00e1ticas comerciais justas. Confira abaixo as condi\u00e7\u00f5es:<\/p>\n<h3 data-start=\"668\" data-end=\"715\">1) Direito de Arrependimento \/ Insatisfa\u00e7\u00e3o<\/h3>\n<p data-start=\"717\" data-end=\"901\">De acordo com o CDC, voc\u00ea tem <strong data-start=\"747\" data-end=\"773\">7 (sete) dias corridos<\/strong>, a partir da data de recebimento do produto, para solicitar a devolu\u00e7\u00e3o ou troca por arrependimento ou insatisfa\u00e7\u00e3o, desde que:<\/p>\n<ul data-start=\"903\" data-end=\"1076\">\n<li data-start=\"903\" data-end=\"950\">\n<p data-start=\"905\" data-end=\"950\">O produto esteja na <strong data-start=\"925\" data-end=\"947\">embalagem original<\/strong>;<\/p>\n<\/li>\n<li data-start=\"951\" data-end=\"979\">\n<p data-start=\"953\" data-end=\"979\"><strong data-start=\"953\" data-end=\"976\">Sem ind\u00edcios de uso<\/strong>;<\/p>\n<\/li>\n<li data-start=\"980\" data-end=\"1035\">\n<p data-start=\"982\" data-end=\"1035\">Com todos os <strong data-start=\"995\" data-end=\"1032\">acess\u00f3rios, manuais e nota fiscal<\/strong>;<\/p>\n<\/li>\n<li data-start=\"1036\" data-end=\"1076\">\n<p data-start=\"1038\" data-end=\"1076\">Em <strong data-start=\"1041\" data-end=\"1075\">perfeito estado de conserva\u00e7\u00e3o<\/strong>.<\/p>\n<\/li>\n<\/ul>\n<p data-start=\"1078\" data-end=\"1280\"><strong data-start=\"1078\" data-end=\"1088\">Frete:<\/strong><br data-start=\"1088\" data-end=\"1091\" \/>O custo do primeiro envio para troca ou devolu\u00e7\u00e3o (dentro do prazo de 7 dias) ser\u00e1 por conta da <strong data-start=\"1187\" data-end=\"1201\">GPK Brasil<\/strong>. A partir da segunda solicita\u00e7\u00e3o, o frete ser\u00e1 de responsabilidade do cliente.<\/p>\n<h3 data-start=\"1282\" data-end=\"1309\">2) Produtos com Defeito<\/h3>\n<p data-start=\"1311\" data-end=\"1400\">Todos os produtos da GPK Brasil possuem <strong data-start=\"1351\" data-end=\"1399\">garantia legal contra defeitos de fabrica\u00e7\u00e3o<\/strong>.<\/p>\n<p data-start=\"1402\" data-end=\"1434\">Caso identifique algum problema:<\/p>\n<p data-start=\"1436\" data-end=\"1614\">Envie um e-mail para <strong data-start=\"1457\" data-end=\"1481\"><a class=\"cursor-pointer\" href=\"mailto:sac@gpkbrasil.com.br\" rel=\"noopener\" data-start=\"1459\" data-end=\"1479\">sac@gpkbrasil.com.br<\/a><\/strong> com fotos ou v\u00eddeos que comprovem o defeito. Se confirmado, providenciaremos a troca ou reparo, conforme disponibilidade em estoque.<\/p>\n<p data-start=\"1616\" data-end=\"1703\"><strong data-start=\"1616\" data-end=\"1631\">Observa\u00e7\u00e3o:<\/strong> A garantia n\u00e3o cobre danos causados por mau uso ou manuseio inadequado.<\/p>\n<h3 data-start=\"1705\" data-end=\"1747\">3) Erro Operacional \/ Pedido Incorreto<\/h3>\n<p data-start=\"1749\" data-end=\"1765\">Se voc\u00ea receber:<\/p>\n<ul data-start=\"1767\" data-end=\"1883\">\n<li data-start=\"1767\" data-end=\"1810\">\n<p data-start=\"1769\" data-end=\"1810\">Um <strong data-start=\"1772\" data-end=\"1793\">produto diferente<\/strong> do solicitado;<\/p>\n<\/li>\n<li data-start=\"1811\" data-end=\"1853\">\n<p data-start=\"1813\" data-end=\"1853\">Um item com <strong data-start=\"1825\" data-end=\"1850\">avaria por transporte<\/strong>;<\/p>\n<\/li>\n<li data-start=\"1854\" data-end=\"1883\">\n<p data-start=\"1856\" data-end=\"1883\">Um <strong data-start=\"1859\" data-end=\"1880\">pedido incompleto<\/strong>;<\/p>\n<\/li>\n<\/ul>\n<p data-start=\"1885\" data-end=\"1991\">Entre em contato em at\u00e9 <strong data-start=\"1909\" data-end=\"1928\">7 dias corridos<\/strong> para solicitar a troca ou devolu\u00e7\u00e3o <strong data-start=\"1965\" data-end=\"1990\">sem custos adicionais<\/strong>.<\/p>\n<h3 data-start=\"1993\" data-end=\"2018\">4) Prazos e Processos<\/h3>\n<p data-start=\"2020\" data-end=\"2129\"><strong data-start=\"2020\" data-end=\"2031\">Trocas:<\/strong><br data-start=\"2031\" data-end=\"2034\" \/>O prazo para envio do novo produto varia conforme disponibilidade em estoque e an\u00e1lise t\u00e9cnica.<\/p>\n<p data-start=\"2131\" data-end=\"2146\"><strong data-start=\"2131\" data-end=\"2146\">Reembolsos:<\/strong><\/p>\n<ul data-start=\"2148\" data-end=\"2334\">\n<li data-start=\"2148\" data-end=\"2200\">\n<p data-start=\"2150\" data-end=\"2200\"><strong data-start=\"2150\" data-end=\"2172\">Cart\u00e3o de cr\u00e9dito:<\/strong> estorno em at\u00e9 2 faturas;<\/p>\n<\/li>\n<li data-start=\"2201\" data-end=\"2264\">\n<p data-start=\"2203\" data-end=\"2264\"><strong data-start=\"2203\" data-end=\"2223\">Dep\u00f3sito ou PIX:<\/strong> cr\u00e9dito em conta em at\u00e9 10 dias \u00fateis;<\/p>\n<\/li>\n<li data-start=\"2265\" data-end=\"2334\">\n<p data-start=\"2267\" data-end=\"2334\"><strong data-start=\"2267\" data-end=\"2277\">Frete:<\/strong> n\u00e3o reembols\u00e1vel em casos de arrependimento ap\u00f3s 7 dias.<\/p>\n<\/li>\n<\/ul>\n<h3 data-start=\"2336\" data-end=\"2380\">5) Produtos N\u00e3o Eleg\u00edveis para Devolu\u00e7\u00e3o<\/h3>\n<p data-start=\"2382\" data-end=\"2444\">Por quest\u00f5es sanit\u00e1rias ou legais, n\u00e3o aceitamos devolu\u00e7\u00e3o de:<\/p>\n<ul data-start=\"2446\" data-end=\"2617\">\n<li data-start=\"2446\" data-end=\"2489\">\n<p data-start=\"2448\" data-end=\"2489\">Produtos de higiene pessoal ou \u00edntimos;<\/p>\n<\/li>\n<li data-start=\"2490\" data-end=\"2531\">\n<p data-start=\"2492\" data-end=\"2531\">Perec\u00edveis (alimentos, flores, etc.);<\/p>\n<\/li>\n<li data-start=\"2532\" data-end=\"2576\">\n<p data-start=\"2534\" data-end=\"2576\">Softwares ou produtos digitais ativados;<\/p>\n<\/li>\n<li data-start=\"2577\" data-end=\"2617\">\n<p data-start=\"2579\" data-end=\"2617\">Itens personalizados ou sob encomenda.<\/p>\n<\/li>\n<\/ul>\n<h3 data-start=\"2619\" data-end=\"2663\">6) Como Solicitar uma Troca ou Devolu\u00e7\u00e3o<\/h3>\n<p data-start=\"2665\" data-end=\"2715\">Envie um e-mail para <a href=\"mailto:sac@gpkbrasil.com.br\"><strong data-start=\"2686\" data-end=\"2710\">sac@gpkbrasil.com.br<\/strong><\/a> com:<\/p>\n<ul data-start=\"2717\" data-end=\"2813\">\n<li data-start=\"2717\" data-end=\"2754\">\n<p data-start=\"2719\" data-end=\"2754\">Nome completo e n\u00famero do pedido;<\/p>\n<\/li>\n<li data-start=\"2755\" data-end=\"2813\">\n<p data-start=\"2757\" data-end=\"2813\">Motivo da devolu\u00e7\u00e3o (em caso de defeito, anexe imagens).<\/p>\n<\/li>\n<\/ul>\n<p data-start=\"2815\" data-end=\"2892\">Voc\u00ea receber\u00e1 um <strong data-start=\"2832\" data-end=\"2854\">c\u00f3digo de postagem<\/strong> (para envio sem custo, se aplic\u00e1vel).<\/p>\n<p data-start=\"2894\" data-end=\"2948\">Reembale o produto com a <strong data-start=\"2919\" data-end=\"2934\">nota fiscal<\/strong> e envie para:<\/p>\n<p data-start=\"2950\" data-end=\"3071\"><strong data-start=\"2950\" data-end=\"2988\">GPK Brasil Pl\u00e1sticos e Pap\u00e9is Ltda<\/strong><br data-start=\"2988\" data-end=\"2991\" \/>Av. Independ\u00eancia, 20 \u2013 Bloco B, Bairro Iporanga<br data-start=\"3039\" data-end=\"3042\" \/>Sorocaba &#8211; SP, CEP: 18087-101<\/p>\n<h3 data-start=\"3073\" data-end=\"3099\">7) Trocas de Presentes<\/h3>\n<p data-start=\"3101\" data-end=\"3261\">Se o produto foi enviado como presente, o reembolso ser\u00e1 feito em forma de <b>vale compras<\/b>.<br data-start=\"3193\" data-end=\"3196\" \/>Caso contr\u00e1rio, o valor ser\u00e1 devolvido ao <strong data-start=\"3238\" data-end=\"3260\">comprador original<\/strong>.<\/p>\n<h3 data-start=\"3263\" data-end=\"3278\">D\u00favidas?<\/h3>\n<p data-start=\"3280\" data-end=\"3367\">Entre em contato:<br data-start=\"3297\" data-end=\"3300\" \/>E-mail: <a class=\"cursor-pointer\" href=\"mailto:sac@gpkbrasil.com.br\" rel=\"noopener\" data-start=\"3310\" data-end=\"3330\">sac@gpkbrasil.com.br<\/a><br data-start=\"3332\" data-end=\"3335\" \/>Telefone: <a href=\"tel:551530323330\">+55 (15) 3032-3330<\/a><\/p>\n<p data-start=\"3369\" data-end=\"3409\">Agradecemos sua confian\u00e7a na GPK Brasil!<\/p>\n<p data-start=\"3411\" data-end=\"3533\"><strong data-start=\"3411\" data-end=\"3420\">Nota:<\/strong> Esta pol\u00edtica est\u00e1 sujeita a altera\u00e7\u00f5es sem aviso pr\u00e9vio. Consulte sempre as condi\u00e7\u00f5es vigentes no site oficial.<\/p>\n<p>\u00a0<\/p>\n\n<\/p>\n<p><\/p><!-- \/wp:post-content -->","protected":false},"excerpt":{"rendered":"<p>A GPK Brasil assegura aos seus clientes uma pol\u00edtica de trocas e devolu\u00e7\u00f5es transparente, em conformidade com o C\u00f3digo de Defesa do Consumidor (CDC) e com pr\u00e1ticas comerciais justas. Confira abaixo as condi\u00e7\u00f5es: 1) Direito de Arrependimento \/ Insatisfa\u00e7\u00e3o De acordo com o CDC, voc\u00ea tem 7 (sete) dias corridos, a partir da data de&#8230;<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_kad_post_transparent":"","_kad_post_title":"","_kad_post_layout":"","_kad_post_sidebar_id":"","_kad_post_content_style":"","_kad_post_vertical_padding":"","_kad_post_feature":"","_kad_post_feature_position":"","_kad_post_header":false,"_kad_post_footer":false,"_kad_post_classname":"","footnotes":""},"class_list":["post-17","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/gpkbrasil.com.br\/b2b\/wp-json\/wp\/v2\/pages\/17","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/gpkbrasil.com.br\/b2b\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/gpkbrasil.com.br\/b2b\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/gpkbrasil.com.br\/b2b\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/gpkbrasil.com.br\/b2b\/wp-json\/wp\/v2\/comments?post=17"}],"version-history":[{"count":0,"href":"https:\/\/gpkbrasil.com.br\/b2b\/wp-json\/wp\/v2\/pages\/17\/revisions"}],"wp:attachment":[{"href":"https:\/\/gpkbrasil.com.br\/b2b\/wp-json\/wp\/v2\/media?parent=17"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}