{"id":125,"count":4,"description":"Na categoria Sustentabilidade &amp; Inova\u00e7\u00e3o voc\u00ea encontra conte\u00fados sobre as iniciativas da GPK Brasil para reduzir impactos ambientais, tecnologias ecol\u00f3gicas aplicadas em nossos produtos e solu\u00e7\u00f5es que unem qualidade e respeito \u00e0 natureza.","link":"https:\/\/gpkbrasil.com.br\/b2b\/category\/sustentabilidade-e-inovacao\/","name":"Sustentabilidade &amp; Inova\u00e7\u00e3o","slug":"sustentabilidade-e-inovacao","taxonomy":"category","parent":0,"meta":[],"_links":{"self":[{"href":"https:\/\/gpkbrasil.com.br\/b2b\/wp-json\/wp\/v2\/categories\/125","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/gpkbrasil.com.br\/b2b\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/gpkbrasil.com.br\/b2b\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/gpkbrasil.com.br\/b2b\/wp-json\/wp\/v2\/posts?categories=125"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}